{"id":2894,"date":"2022-06-13T16:47:36","date_gmt":"2022-06-13T15:47:36","guid":{"rendered":"http:\/\/newvoicetest.online\/applications\/"},"modified":"2025-07-23T09:43:30","modified_gmt":"2025-07-23T08:43:30","slug":"fonctionnalites","status":"publish","type":"page","link":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/","title":{"rendered":"Fonctionnalit\u00e9s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2894\" class=\"elementor elementor-2894 elementor-344\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0668ce4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0668ce4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-518885c\" data-id=\"518885c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-576be79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"576be79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34c5228\" data-id=\"34c5228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be029db elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"be029db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos fonctionnalit\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-76de71f\" data-id=\"76de71f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a70fa8d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a70fa8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>New Voice propose une gamme de fonctionnalit\u00e9s con\u00e7ues pour garantir la s\u00e9curit\u00e9 de vos employ\u00e9s et de votre \u00e9quipement, les prot\u00e9geant ainsi des dangers potentiels.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dc235b animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6dc235b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-91c1d05\" data-id=\"91c1d05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7a34c33\" data-id=\"7a34c33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37bc522 eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"37bc522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/trousse-de-premiers-secours.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Gestion des appels d\u2019urgences<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                            <\/div>\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/gestion-des-urgences\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8615dd0 elementor-invisible\" data-id=\"8615dd0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7be4068 eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"7be4068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/alarme-incendie.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Alertes aux incendies<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/alerte-incendie-et-catastrophe\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f1e3d01\" data-id=\"f1e3d01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e939a2c eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"e939a2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/ouvrier-du-batiment.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Protection travailleurs isol\u00e9s<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                            <\/div>\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/protection-des-travailleurs-isoles\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-22a151d\" data-id=\"22a151d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d36823c animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d36823c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_opacity_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_opacity_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;background_motion_fx_opacity_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:80,&quot;end&quot;:80}},&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;background_motion_fx_opacity_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fb3d0dd\" data-id=\"fb3d0dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab8cbf elementor-widget__width-initial eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"7ab8cbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/infirmiere.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Appels malades<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                            <\/div>\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/systemes-dappel-malade\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-baa47a5\" data-id=\"baa47a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74f1838 eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"74f1838\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/continuous-1.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Gestion de la continuit\u00e9 des activit\u00e9s<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                            <\/div>\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/gestion-de-la-continuite-des-activites\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9a8b563\" data-id=\"9a8b563\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09ae2dd eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"09ae2dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/muet-1.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Alarme Silencieuse<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/alarme-silencieuse\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e105350\" data-id=\"e105350\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89aae8f eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"89aae8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/batiment-1.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Gestion technique des b\u00e2timents<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/gestion-technique-des-batiments\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e39adf8 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"e39adf8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-dbbf163\" data-id=\"dbbf163\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7428a2f\" data-id=\"7428a2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1676171 eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"1676171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/gestion-du-temps-1.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Gestion des incidents<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                            <\/div>\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/gestion-des-incidents\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a425579\" data-id=\"a425579\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-611eae9 eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"611eae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/un-service-en-ligne-1.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Voix sur IP<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                            <\/div>\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"https:\/\/newvoiceinternational.com\/fr\/systemes-dappel-de-service\/\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-597bac8\" data-id=\"597bac8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9ce5c1 eael-flipbox-content-align-center eael-flipbox-img-default elementor-widget elementor-widget-eael-flip-box\" data-id=\"b9ce5c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-fade-in eael-content eael-flip-box-hover eael-flipbox-fixed-height eael-flipbox-dynamic\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n                    \n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <img decoding=\"async\" class=\"eael-flipbox-image-as-icon\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/smartphone.png\" alt=\"\">\n                                                                            <\/div>\n                                    <h2 class=\"eael-elements-flip-box-heading\">Syst\u00e8me de localisation<\/h2>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n                                                                <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                            <\/div>\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"_wp_link_placeholder\">D\u00e9couvrez plus<\/a><\/span><\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f7e0f27\" data-id=\"f7e0f27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos fonctionnalit\u00e9s New Voice propose une gamme de fonctionnalit\u00e9s con\u00e7ues pour garantir la s\u00e9curit\u00e9 de vos employ\u00e9s et de votre \u00e9quipement, les prot\u00e9geant ainsi des dangers potentiels. Gestion des appels d\u2019urgences D\u00e9couvrez plus Alertes aux incendies D\u00e9couvrez plus Protection travailleurs isol\u00e9s D\u00e9couvrez plus Appels malades D\u00e9couvrez plus Gestion de la continuit\u00e9 des activit\u00e9s D\u00e9couvrez plus [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_eb_attr":"","inline_featured_image":false,"footnotes":""},"class_list":["post-2894","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fonctionnalit\u00e9s - NewVoice International<\/title>\n<meta name=\"description\" content=\"New Voice International - Alarm Solutions, Safety Systems, Lone Worker Protection, Silent Alarmas, Indoor Positioning, Nurse Call Systems, Emergeny Systems\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fonctionnalit\u00e9s - NewVoice International\" \/>\n<meta property=\"og:description\" content=\"New Voice International - Alarm Solutions, Safety Systems, Lone Worker Protection, Silent Alarmas, Indoor Positioning, Nurse Call Systems, Emergeny Systems\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/\" \/>\n<meta property=\"og:site_name\" content=\"NewVoice International\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T08:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/trousse-de-premiers-secours.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/\",\"name\":\"Fonctionnalit\u00e9s - NewVoice International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/trousse-de-premiers-secours.png\",\"datePublished\":\"2022-06-13T15:47:36+00:00\",\"dateModified\":\"2025-07-23T08:43:30+00:00\",\"description\":\"New Voice International - Alarm Solutions, Safety Systems, Lone Worker Protection, Silent Alarmas, Indoor Positioning, Nurse Call Systems, Emergeny Systems\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/trousse-de-premiers-secours.png\",\"contentUrl\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/trousse-de-premiers-secours.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/fonctionnalites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fonctionnalit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/\",\"name\":\"NewVoice International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#organization\",\"name\":\"NewVoice International\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/NV_Logo_RGB.png\",\"contentUrl\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/NV_Logo_RGB.png\",\"width\":1200,\"height\":315,\"caption\":\"NewVoice International\"},\"image\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fonctionnalit\u00e9s - NewVoice International","description":"New Voice International - Alarm Solutions, Safety Systems, Lone Worker Protection, Silent Alarmas, Indoor Positioning, Nurse Call Systems, Emergeny Systems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/","og_locale":"fr_FR","og_type":"article","og_title":"Fonctionnalit\u00e9s - NewVoice International","og_description":"New Voice International - Alarm Solutions, Safety Systems, Lone Worker Protection, Silent Alarmas, Indoor Positioning, Nurse Call Systems, Emergeny Systems","og_url":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/","og_site_name":"NewVoice International","article_modified_time":"2025-07-23T08:43:30+00:00","og_image":[{"url":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/trousse-de-premiers-secours.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/","url":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/","name":"Fonctionnalit\u00e9s - NewVoice International","isPartOf":{"@id":"https:\/\/newvoiceinternational.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/#primaryimage"},"image":{"@id":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/#primaryimage"},"thumbnailUrl":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/trousse-de-premiers-secours.png","datePublished":"2022-06-13T15:47:36+00:00","dateModified":"2025-07-23T08:43:30+00:00","description":"New Voice International - Alarm Solutions, Safety Systems, Lone Worker Protection, Silent Alarmas, Indoor Positioning, Nurse Call Systems, Emergeny Systems","breadcrumb":{"@id":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/#primaryimage","url":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/trousse-de-premiers-secours.png","contentUrl":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/11\/trousse-de-premiers-secours.png"},{"@type":"BreadcrumbList","@id":"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newvoiceinternational.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Fonctionnalit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/newvoiceinternational.com\/fr\/#website","url":"https:\/\/newvoiceinternational.com\/fr\/","name":"NewVoice International","description":"","publisher":{"@id":"https:\/\/newvoiceinternational.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newvoiceinternational.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/newvoiceinternational.com\/fr\/#organization","name":"NewVoice International","url":"https:\/\/newvoiceinternational.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newvoiceinternational.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2022\/06\/NV_Logo_RGB.png","contentUrl":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2022\/06\/NV_Logo_RGB.png","width":1200,"height":315,"caption":"NewVoice International"},"image":{"@id":"https:\/\/newvoiceinternational.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/pages\/2894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/comments?post=2894"}],"version-history":[{"count":0,"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/pages\/2894\/revisions"}],"wp:attachment":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/media?parent=2894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}