{"id":2890,"date":"2022-06-08T12:49:21","date_gmt":"2022-06-08T11:49:21","guid":{"rendered":"http:\/\/newvoicetest.online\/our-services\/"},"modified":"2025-09-08T09:45:55","modified_gmt":"2025-09-08T08:45:55","slug":"solutions","status":"publish","type":"page","link":"https:\/\/newvoiceinternational.com\/fr\/solutions\/","title":{"rendered":"Nos Solutions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2890\" class=\"elementor elementor-2890 elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fcad7f7 elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"5fcad7f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fb492a4\" data-id=\"2fb492a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597735bc elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"597735bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nos solutions<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4da9229 elementor-widget elementor-widget-text-editor\" data-id=\"4da9229\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez notre gamme de services !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7891fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7891fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3c96c19\" data-id=\"3c96c19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46d4543 elementor-widget elementor-widget-image\" data-id=\"46d4543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/www.newvoiceinternational.com\/fr\/applications\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"580\" height=\"326\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-1024x576.jpg\" class=\"attachment-large size-large wp-image-30082\" alt=\"\" srcset=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-1024x576.jpg 1024w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-300x169.jpg 300w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-768x432.jpg 768w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-1200x675.jpg 1200w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2.jpg 1366w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ccdac3 elementor-widget elementor-widget-text-editor\" data-id=\"2ccdac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong><a style=\"color: #ffffff;\" href=\"https:\/\/newvoiceinternational.com\/fr\/fonctionnalites\/\" target=\"_blank\" rel=\"noopener\">Fonctionnalit\u00e9s<\/a><\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c8edc4\" data-id=\"4c8edc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-422f958 elementor-widget elementor-widget-image\" data-id=\"422f958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.newvoiceinternational.com\/fr\/industries\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"326\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/3-1024x576.jpg\" class=\"attachment-large size-large wp-image-30085\" alt=\"\" srcset=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/3-1024x576.jpg 1024w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/3-300x169.jpg 300w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/3-768x432.jpg 768w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/3-1200x675.jpg 1200w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/3.jpg 1366w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e186602 elementor-widget elementor-widget-text-editor\" data-id=\"e186602\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/newvoiceinternational.com\/fr\/secteursactivites\/\"><strong>Secteurs d&rsquo;activit\u00e9s<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c960e5a\" data-id=\"c960e5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9467e80 elementor-widget elementor-widget-image\" data-id=\"9467e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/newvoiceinternational.com\/fr\/produits\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"326\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/4-1024x576.jpg\" class=\"attachment-large size-large wp-image-30088\" alt=\"\" srcset=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/4-1024x576.jpg 1024w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/4-300x169.jpg 300w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/4-768x432.jpg 768w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/4-1200x675.jpg 1200w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/4.jpg 1366w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5213c98 elementor-widget elementor-widget-text-editor\" data-id=\"5213c98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/newvoiceinternational.com\/fr\/plateformes\/\"><strong>Plateformes<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53134b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53134b0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da7f696\" data-id=\"da7f696\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0961af elementor-widget elementor-widget-toggle\" data-id=\"f0961af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2521\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2521\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pourquoi choisir New Voice ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2521\">Depuis sa fondation en 1991, New Voice utilise une norme de qualit\u00e9 suisse pour s&rsquo;engager sur la fiabilit\u00e9, l&rsquo;innovation, la satisfaction client et l&rsquo;optimisation des processus. Tout ce que nous faisons depuis plus de 30 ans vise \u00e0 rendre le monde plus s\u00e9curis\u00e9. Comp\u00e9tence, exp\u00e9rience et modularit\u00e9 font de nous votre partenaire d&rsquo;avenir. D\u00e9couvrez plus sur New Voice\u00a0: https:\/\/newvoiceinternational.com\/fr\/about-us\/<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2522\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2522\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qu'est-ce qu'un syst\u00e8me de localisation int\u00e9rieure ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2522\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2522\">Un syst\u00e8me de localisation int\u00e9rieure est une ou plusieurs technologies diff\u00e9rentes install\u00e9es dans des espaces clos, qui permettent de localiser non seulement des biens ou des personnes dans des positions fixes, mais aussi des personnes ou des \u00e9quipements en mouvement. Un syst\u00e8me de localisation int\u00e9rieure vous permet de localiser vos employ\u00e9s, vos clients et vos actifs dans des espaces ferm\u00e9s.\n\nLes syst\u00e8mes de localisation int\u00e9rieure utilisent des combinaison de technologies, notamment le WiFi, le Bluetooth, le NFC, les \u00e9tiquettes DECT et le GPS, pour calculer l&#8217;emplacement d&rsquo;un dispositif ou d&rsquo;une personne. Le GPS, par exemple, est la technologie parfaite pour le suivi en ext\u00e9rieur, tandis que d&rsquo;autres technologies sont plus utilis\u00e9es pour le suivi en int\u00e9rieur.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2523\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2523\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pourquoi un syst\u00e8me de localisation int\u00e9rieure est-il important\/n\u00e9cessaire ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2523\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2523\">Un syst\u00e8me de  localisation int\u00e9rieure vous permet d&rsquo;\u00eatre plus pr\u00e9cis dans la localisation de vos employ\u00e9s, clients et actifs dans des environnements o\u00f9 la navigation par satellite \u00e9choue. Le plus haut niveau de s\u00e9curit\u00e9 est garanti et les entreprises sont soutenues pour \u00e9viter les situations dangereuses.\nD\u00e9couvrez plus d&rsquo;avantages sur la localisation int\u00e9rieure ici https:\/\/www.newvoiceinternational.com\/indoor-positioning-benefits\/<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2524\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2524\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quels sont les avantages d'une alarme silencieuse ? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2524\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2524\"><p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1. Les intrus ne remarqueront pas l'alarme\\n2. Vos voisins ne seront pas d\u00e9rang\u00e9s\\n3. Il informe automatiquement la police ou les services de s\u00e9curit\u00e9 appropri\u00e9s\\n4. CCTV permet l'identification des intrus\\n5. L'alarme silencieuse peut \u00eatre facilement int\u00e9gr\u00e9e \u00e0 votre infrastructure de s\u00e9curit\u00e9 existante&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14721,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;10&quot;:0,&quot;11&quot;:4,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">1. Les intrus ne remarqueront pas l&rsquo;alarme<br \/>2. Vos voisins ne seront pas d\u00e9rang\u00e9s<br \/>3. Il informe automatiquement la police ou les services de s\u00e9curit\u00e9 appropri\u00e9s<br \/>4. CCTV permet l&rsquo;identification des intrus<br \/>5. L&rsquo;alarme silencieuse peut \u00eatre facilement int\u00e9gr\u00e9e \u00e0 votre infrastructure de s\u00e9curit\u00e9 existante<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2525\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2525\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qu'est-ce qu'une alarme silencieuse ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2525\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2525\"><p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Une alarme silencieuse est un syst\u00e8me automatique qui d\u00e9clenche une alarme lorsqu'il d\u00e9tecte une faille de s\u00e9curit\u00e9 sans causer de bruit ou de signes visuels - ce qui rend difficile la d\u00e9tection des intrus. Il est difficile de l'ignorer car il envoie un signal automatique \u00e0 la police ou avertit votre services de s\u00e9curit\u00e9. C'est l'aspect le plus important de l'alarme silencieuse - les intrus ne se doutent de rien jusqu'\u00e0 ce que la police arrive et intervienne. En attendant, vos employ\u00e9s sont prot\u00e9g\u00e9s car les intrus ne paniquent pas lorsqu'ils entendent des alarmes sonores dans les locaux.\\n\\nL'alarme silencieuse peut \u00eatre int\u00e9gr\u00e9e \u00e0 votre syst\u00e8me de s\u00e9curit\u00e9 ou \u00eatre une solution autonome pour votre entreprise.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14721,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;10&quot;:0,&quot;11&quot;:4,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">Une alarme silencieuse est un syst\u00e8me automatique qui d\u00e9clenche une alarme lorsqu&rsquo;il d\u00e9tecte une faille de s\u00e9curit\u00e9 sans causer de bruit ou de signes visuels &#8211; ce qui rend difficile la d\u00e9tection des intrus. Il est difficile de l&rsquo;ignorer car il envoie un signal automatique \u00e0 la police ou avertit votre services de s\u00e9curit\u00e9. C&rsquo;est l&rsquo;aspect le plus important de l&rsquo;alarme silencieuse &#8211; les intrus ne se doutent de rien jusqu&rsquo;\u00e0 ce que la police arrive et intervienne. En attendant, vos employ\u00e9s sont prot\u00e9g\u00e9s car les intrus ne paniquent pas lorsqu&rsquo;ils entendent des alarmes sonores dans les locaux.<\/span><\/p><p>L&rsquo;alarme silencieuse peut \u00eatre int\u00e9gr\u00e9e \u00e0 votre syst\u00e8me de s\u00e9curit\u00e9 ou \u00eatre une solution autonome pour votre entreprise.<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3661db4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3661db4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f94c664\" data-id=\"f94c664\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08475b8 elementor-widget elementor-widget-heading\" data-id=\"08475b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contactez-nous !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb0dae3 elementor-button-align-start elementor-widget__width-initial elementor-widget elementor-widget-form\" data-id=\"eb0dae3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"contactform\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2890\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"eb0dae3\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Nos Solutions - NewVoice International\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"2890\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_d53ccf7 elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_d53ccf7\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_d53ccf7]\" id=\"form-field-field_d53ccf7\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_0be24ec elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_0be24ec\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPr\u00e9nom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_0be24ec]\" id=\"form-field-field_0be24ec\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Pr\u00e9nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha elementor-field-group elementor-column elementor-field-group-field_9a29b34 elementor-col-100\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_9a29b34\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6Ldzg_MhAAAAAJAuFjZPm8EFetGy2Fv-TLB8xb8k\" data-type=\"v2_checkbox\" data-theme=\"light\" data-size=\"normal\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyez<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9291d2e\" data-id=\"9291d2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-357b089 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"357b089\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-920fd66\" data-id=\"920fd66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4929bbd elementor-widget elementor-widget-image\" data-id=\"4929bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2025\/07\/NV_Icon_pos_RGB.png\" class=\"attachment-full size-full wp-image-49999\" alt=\"\" srcset=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2025\/07\/NV_Icon_pos_RGB.png 1200w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2025\/07\/NV_Icon_pos_RGB-300x300.png 300w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2025\/07\/NV_Icon_pos_RGB-1024x1024.png 1024w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2025\/07\/NV_Icon_pos_RGB-150x150.png 150w, https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2025\/07\/NV_Icon_pos_RGB-768x768.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos solutions D\u00e9couvrez notre gamme de services ! Fonctionnalit\u00e9s Secteurs d&rsquo;activit\u00e9s Plateformes Pourquoi choisir New Voice ? Depuis sa fondation en 1991, New Voice utilise une norme de qualit\u00e9 suisse pour s&#8217;engager sur la fiabilit\u00e9, l&#8217;innovation, la satisfaction client et l&#8217;optimisation des processus. Tout ce que nous faisons depuis plus de 30 ans vise \u00e0 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_eb_attr":"","inline_featured_image":false,"footnotes":""},"class_list":["post-2890","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos Solutions - NewVoice International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newvoiceinternational.com\/fr\/solutions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos Solutions - NewVoice International\" \/>\n<meta property=\"og:description\" content=\"Nos solutions D\u00e9couvrez notre gamme de services ! Fonctionnalit\u00e9s Secteurs d&rsquo;activit\u00e9s Plateformes Pourquoi choisir New Voice ? Depuis sa fondation en 1991, New Voice utilise une norme de qualit\u00e9 suisse pour s&#8217;engager sur la fiabilit\u00e9, l&#8217;innovation, la satisfaction client et l&#8217;optimisation des processus. Tout ce que nous faisons depuis plus de 30 ans vise \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newvoiceinternational.com\/fr\/solutions\/\" \/>\n<meta property=\"og:site_name\" content=\"NewVoice International\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T08:45:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/\",\"name\":\"Nos Solutions - NewVoice International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/2-1024x576.jpg\",\"datePublished\":\"2022-06-08T11:49:21+00:00\",\"dateModified\":\"2025-09-08T08:45:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/2-1024x576.jpg\",\"contentUrl\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/2-1024x576.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/solutions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos Solutions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/\",\"name\":\"NewVoice International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#organization\",\"name\":\"NewVoice International\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/NV_Logo_RGB.png\",\"contentUrl\":\"https:\\\/\\\/newvoiceinternational.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/NV_Logo_RGB.png\",\"width\":1200,\"height\":315,\"caption\":\"NewVoice International\"},\"image\":{\"@id\":\"https:\\\/\\\/newvoiceinternational.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos Solutions - NewVoice International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newvoiceinternational.com\/fr\/solutions\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos Solutions - NewVoice International","og_description":"Nos solutions D\u00e9couvrez notre gamme de services ! Fonctionnalit\u00e9s Secteurs d&rsquo;activit\u00e9s Plateformes Pourquoi choisir New Voice ? Depuis sa fondation en 1991, New Voice utilise une norme de qualit\u00e9 suisse pour s&#8217;engager sur la fiabilit\u00e9, l&#8217;innovation, la satisfaction client et l&#8217;optimisation des processus. Tout ce que nous faisons depuis plus de 30 ans vise \u00e0 [&hellip;]","og_url":"https:\/\/newvoiceinternational.com\/fr\/solutions\/","og_site_name":"NewVoice International","article_modified_time":"2025-09-08T08:45:55+00:00","og_image":[{"width":1366,"height":768,"url":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newvoiceinternational.com\/fr\/solutions\/","url":"https:\/\/newvoiceinternational.com\/fr\/solutions\/","name":"Nos Solutions - NewVoice International","isPartOf":{"@id":"https:\/\/newvoiceinternational.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newvoiceinternational.com\/fr\/solutions\/#primaryimage"},"image":{"@id":"https:\/\/newvoiceinternational.com\/fr\/solutions\/#primaryimage"},"thumbnailUrl":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-1024x576.jpg","datePublished":"2022-06-08T11:49:21+00:00","dateModified":"2025-09-08T08:45:55+00:00","breadcrumb":{"@id":"https:\/\/newvoiceinternational.com\/fr\/solutions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newvoiceinternational.com\/fr\/solutions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newvoiceinternational.com\/fr\/solutions\/#primaryimage","url":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-1024x576.jpg","contentUrl":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2023\/09\/2-1024x576.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/newvoiceinternational.com\/fr\/solutions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newvoiceinternational.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nos Solutions"}]},{"@type":"WebSite","@id":"https:\/\/newvoiceinternational.com\/fr\/#website","url":"https:\/\/newvoiceinternational.com\/fr\/","name":"NewVoice International","description":"","publisher":{"@id":"https:\/\/newvoiceinternational.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newvoiceinternational.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/newvoiceinternational.com\/fr\/#organization","name":"NewVoice International","url":"https:\/\/newvoiceinternational.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newvoiceinternational.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2022\/06\/NV_Logo_RGB.png","contentUrl":"https:\/\/newvoiceinternational.com\/wp-content\/uploads\/2022\/06\/NV_Logo_RGB.png","width":1200,"height":315,"caption":"NewVoice International"},"image":{"@id":"https:\/\/newvoiceinternational.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/pages\/2890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/comments?post=2890"}],"version-history":[{"count":0,"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/pages\/2890\/revisions"}],"wp:attachment":[{"href":"https:\/\/newvoiceinternational.com\/fr\/wp-json\/wp\/v2\/media?parent=2890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}